{"id":1422,"count":1,"description":"","link":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/","name":"Usurpaci\u00f3n de la presidencia","slug":"usurpacion-de-la-presidencia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Usurpaci\u00f3n de la presidencia - Pedro A. Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usurpaci\u00f3n de la presidencia - Pedro A. Palma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro A. Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/tag\\\/usurpacion-de-la-presidencia\\\/\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/tag\\\/usurpacion-de-la-presidencia\\\/\",\"name\":\"Usurpaci\u00f3n de la presidencia - Pedro A. Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/tag\\\/usurpacion-de-la-presidencia\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/tag\\\/usurpacion-de-la-presidencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Usurpaci\u00f3n de la presidencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\",\"name\":\"Pedro A. Palma\",\"description\":\"Economista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Usurpaci\u00f3n de la presidencia - Pedro A. Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/","og_locale":"es_ES","og_type":"article","og_title":"Usurpaci\u00f3n de la presidencia - Pedro A. Palma","og_url":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/","og_site_name":"Pedro A. Palma","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/","url":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/","name":"Usurpaci\u00f3n de la presidencia - Pedro A. Palma","isPartOf":{"@id":"https:\/\/pedroapalma.com\/site\/#website"},"breadcrumb":{"@id":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/pedroapalma.com\/site\/tag\/usurpacion-de-la-presidencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pedroapalma.com\/site\/"},{"@type":"ListItem","position":2,"name":"Usurpaci\u00f3n de la presidencia"}]},{"@type":"WebSite","@id":"https:\/\/pedroapalma.com\/site\/#website","url":"https:\/\/pedroapalma.com\/site\/","name":"Pedro A. Palma","description":"Economista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedroapalma.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/tags\/1422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts?tags=1422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}