{"id":4177,"date":"2018-04-01T12:04:10","date_gmt":"2018-04-01T16:34:10","guid":{"rendered":"http:\/\/www.pedroapalma.com\/?p=4177"},"modified":"2018-04-01T12:10:02","modified_gmt":"2018-04-01T16:40:02","slug":"jose-antonio-abreu-inmortal","status":"publish","type":"post","link":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/","title":{"rendered":"Jos\u00e9 Antonio Abreu, inmortal"},"content":{"rendered":"<p>Publicado en el diario \u201cEl Nacional\u201d de Caracas. Domingo 1 de abril de 2018<\/p>\n<p>Pocas veces tiene uno la suerte de encontrarse con personas excepcionales que con su obra dejan una huella imborrable y perdurable, haci\u00e9ndolos inmortales. Yo tuve la suerte de conocer y entablar una estrecha y larga amistad con uno de esos portentos: Jos\u00e9 Antonio Abreu, quien acaba de fallecer, dejando tras de s\u00ed una obra excepcional, como es El Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela, tambi\u00e9n conocido mundialmente como El Sistema.<br \/>\nLo conoc\u00ed en 1962, cuando al comienzo de mis estudios de Econom\u00eda tuve la suerte de tenerlo como profesor de Teor\u00eda Econ\u00f3mica, pudiendo por ello decir que fue \u00e9l quien me ense\u00f1\u00f3 las primeras nociones de esa fascinante ciencia a la que le he dedicado mi vida profesional. Ulteriormente, Jos\u00e9 Antonio me invit\u00f3 a desempe\u00f1arme como preparador de esa c\u00e1tedra y, despu\u00e9s de graduarme, a compartir con \u00e9l la ense\u00f1anza de esa materia fundamental. En esos a\u00f1os, sin embargo, no era esa su \u00fanica ocupaci\u00f3n profesional; adem\u00e1s de la m\u00fasica y de su actividad docente y de investigaci\u00f3n en la Universidad Cat\u00f3lica Andr\u00e9s Bello, la pol\u00edtica absorb\u00eda buena parte de su tiempo. Si bien se destacaba en toda esa diversidad de funciones, era obvio que su gran talento no se estaba utilizando en forma plena y eficiente. De all\u00ed que quienes lo conoc\u00edamos expres\u00e1bamos que el d\u00eda que \u00e9l le dedicara todos sus esfuerzos a una actividad \u00fanica, los resultados ser\u00edan excepcionales.<br \/>\nPara buena fortuna de Venezuela, a mediados de los a\u00f1os setenta Jos\u00e9 Antonio decidi\u00f3 concentrarse en la docencia y promoci\u00f3n de la m\u00fasica. Fue as\u00ed como naci\u00f3 El Sistema, que hoy es reconocido como uno de los fen\u00f3menos musicales de mayor relevancia a nivel global, habi\u00e9ndose propagado en m\u00faltiples pa\u00edses del orbe. En febrero de 1975 \u00e9l reuni\u00f3 a un pu\u00f1ado de j\u00f3venes m\u00fasicos, gest\u00e1ndose as\u00ed lo que despu\u00e9s pas\u00f3 a ser la Orquesta Sinf\u00f3nica Sim\u00f3n Bol\u00edvar, la cual, con el pasar del tiempo se transform\u00f3 en una agrupaci\u00f3n madura y de alto rango. A lo largo de estas \u00faltimas cuatro d\u00e9cadas, ese extraordinario movimiento ha crecido en forma sostenida, contando hoy con un extraordinario equipo de maestros que ense\u00f1a y gu\u00eda a m\u00e1s de 800.000 ni\u00f1os y j\u00f3venes. Una granada selecci\u00f3n de peque\u00f1os m\u00fasicos form\u00f3 hace m\u00e1s de veinte a\u00f1os la Orquesta Nacional Infantil de Venezuela, la cual dej\u00f3 maravillados a todos los que la escucharon durante sus m\u00faltiples giras internacionales, siendo catalogada como una de las mejores del mundo en su g\u00e9nero. En los a\u00f1os que siguieron, otras orquestas, tanto juveniles como infantiles, continuaron asombrando al mundo con sus extraordinarias interpretaciones de las m\u00e1s exigentes obras de la m\u00fasica acad\u00e9mica.<br \/>\nPero la obra de Abreu va mucho m\u00e1s all\u00e1 de lo musical. El Sistema tambi\u00e9n tiene un importante componente social, pues a los ni\u00f1os que participan en \u00e9l se les inculca, adem\u00e1s del amor a la m\u00fasica y a la est\u00e9tica, un sentido de disciplina, trabajo en equipo, compa\u00f1erismo y, sobre todo, afianzamiento de la personalidad. Dado que la mayor\u00eda de los participantes provienen de los estratos menos favorecidos de la poblaci\u00f3n, es notable observar c\u00f3mo la formaci\u00f3n que reciben los ayuda a trazarse metas, a superarse y a sentir autoestima. En palabras de Abreu: \u201cEl instrumento musical y la orquesta convierten al ni\u00f1o pobre-material en un rico-espiritual, y esa riqueza lo prepara para un salto cualitativo, tanto en su vida intelectual como en su visi\u00f3n de la sociedad y, sobre todo, en su capacidad para superar la pobreza\u201d.<br \/>\nLa partida del amigo me llena de tristeza, pero a la vez me reconforta saber que aquella predicci\u00f3n que manifest\u00e1bamos sus amigos hace ya m\u00e1s de cincuenta a\u00f1os, no solo se hizo realidad, sino que la obra que cre\u00f3 y foment\u00f3 al dedicar todo su esfuerzo y raz\u00f3n de vida a la educaci\u00f3n musical, adem\u00e1s de excepcional, lo inmortaliz\u00f3, pues su nombre ya est\u00e1 y perdurar\u00e1 en la lista de los grandes propulsores universales de la m\u00fasica.<\/p>\n<h6>Imagen: Fundamusical.org.ve<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo que hace honor a Jos\u00e9 Antonio Abreu, venezolano ilustre recientemente fallecido, quien fue creador y director del Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela, tambi\u00e9n conocido como \u201cEl Sistema\u201d. Esta portentosa obra, admirada y reproducida en el mundo entero, hizo inmortal al maestro Abreu.<\/p>\n","protected":false},"author":2,"featured_media":4180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,25,11,18],"tags":[1392,292,293,204,1393],"class_list":["post-4177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-opinion","category-aspectos-sociales","category-opinion","category-personajes","tag-el-sistema","tag-jose-antonio-abreu","tag-maestro-abreu","tag-musica","tag-sistema-nacional-de-orquestas-y-coros-juveniles-e-infantiles-de-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo que hace honor a Jos\u00e9 Antonio Abreu, venezolano ilustre recientemente fallecido, quien fue creador y director del Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela, tambi\u00e9n conocido como \u201cEl Sistema\u201d. Esta portentosa obra, admirada y reproducida en el mundo entero, hizo inmortal al maestro Abreu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro A. Palma\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-01T16:34:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-01T16:40:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/\"},\"author\":{\"name\":\"Pedro Palma\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\"},\"headline\":\"Jos\u00e9 Antonio Abreu, inmortal\",\"datePublished\":\"2018-04-01T16:34:10+00:00\",\"dateModified\":\"2018-04-01T16:40:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/\"},\"wordCount\":748,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/JAAbreu-Fundamusical.org_.ve_.jpg\",\"keywords\":[\"El Sistema\",\"Jos\u00e9 Antonio Abreu\",\"Maestro Abreu\",\"M\u00fasica\",\"Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela\"],\"articleSection\":[\"Art\u00edculos de opini\u00f3n\",\"Aspectos sociales\",\"Opini\u00f3n\",\"Personajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/\",\"name\":\"Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/JAAbreu-Fundamusical.org_.ve_.jpg\",\"datePublished\":\"2018-04-01T16:34:10+00:00\",\"dateModified\":\"2018-04-01T16:40:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/JAAbreu-Fundamusical.org_.ve_.jpg\",\"contentUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/JAAbreu-Fundamusical.org_.ve_.jpg\",\"width\":630,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/jose-antonio-abreu-inmortal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Antonio Abreu, inmortal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\",\"name\":\"Pedro A. Palma\",\"description\":\"Economista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\",\"name\":\"Pedro Palma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"caption\":\"Pedro Palma\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma","og_description":"Art\u00edculo que hace honor a Jos\u00e9 Antonio Abreu, venezolano ilustre recientemente fallecido, quien fue creador y director del Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela, tambi\u00e9n conocido como \u201cEl Sistema\u201d. Esta portentosa obra, admirada y reproducida en el mundo entero, hizo inmortal al maestro Abreu.","og_url":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/","og_site_name":"Pedro A. Palma","article_published_time":"2018-04-01T16:34:10+00:00","article_modified_time":"2018-04-01T16:40:02+00:00","og_image":[{"width":630,"height":432,"url":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg","type":"image\/jpeg"}],"author":"Pedro Palma","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pedro Palma","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#article","isPartOf":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/"},"author":{"name":"Pedro Palma","@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228"},"headline":"Jos\u00e9 Antonio Abreu, inmortal","datePublished":"2018-04-01T16:34:10+00:00","dateModified":"2018-04-01T16:40:02+00:00","mainEntityOfPage":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/"},"wordCount":748,"commentCount":0,"image":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#primaryimage"},"thumbnailUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg","keywords":["El Sistema","Jos\u00e9 Antonio Abreu","Maestro Abreu","M\u00fasica","Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela"],"articleSection":["Art\u00edculos de opini\u00f3n","Aspectos sociales","Opini\u00f3n","Personajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/","url":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/","name":"Jos\u00e9 Antonio Abreu, inmortal - Pedro A. Palma","isPartOf":{"@id":"https:\/\/pedroapalma.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#primaryimage"},"image":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#primaryimage"},"thumbnailUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg","datePublished":"2018-04-01T16:34:10+00:00","dateModified":"2018-04-01T16:40:02+00:00","author":{"@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228"},"breadcrumb":{"@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#primaryimage","url":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg","contentUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2018\/04\/JAAbreu-Fundamusical.org_.ve_.jpg","width":630,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/pedroapalma.com\/site\/jose-antonio-abreu-inmortal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pedroapalma.com\/site\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Antonio Abreu, inmortal"}]},{"@type":"WebSite","@id":"https:\/\/pedroapalma.com\/site\/#website","url":"https:\/\/pedroapalma.com\/site\/","name":"Pedro A. Palma","description":"Economista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedroapalma.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228","name":"Pedro Palma","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","caption":"Pedro Palma"}}]}},"_links":{"self":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/4177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/comments?post=4177"}],"version-history":[{"count":1,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/4177\/revisions"}],"predecessor-version":[{"id":4181,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/4177\/revisions\/4181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/media\/4180"}],"wp:attachment":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/media?parent=4177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/categories?post=4177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/tags?post=4177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}