{"id":176,"date":"2015-09-24T18:51:59","date_gmt":"2015-09-24T18:51:59","guid":{"rendered":"http:\/\/www.tmsdesarrolladores.com\/pedropalma\/?p=176"},"modified":"2015-09-30T18:30:46","modified_gmt":"2015-09-30T18:30:46","slug":"el-contrabando-fronterizo","status":"publish","type":"post","link":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/","title":{"rendered":"El contrabando fronterizo"},"content":{"rendered":"<p>Una de las razones que ha aducido el gobierno venezolano para justificar el cierre de la frontera con Colombia es eliminar la desviaci\u00f3n masiva de productos venezolanos hacia el vecino pa\u00eds, lo cual genera escasez y desabastecimiento en los mercados locales y presiones alcista de los precios internos. De all\u00ed que sea v\u00e1lido que nos preguntemos si esa acci\u00f3n realmente va a eliminar el llamado contrabando de extracci\u00f3n de lo que aqu\u00ed se produce hacia Colombia, o no. Realmente, no lo creo.<\/p>\n<p>Lo que siempre se ha producido en esa frontera, particularmente en el T\u00e1chira, es un proceso de arbitraje, seg\u00fan el cual los habitantes de ambos lados de la zona se preguntan d\u00f3nde conviene m\u00e1s adquirir los productos requeridos para satisfacer sus necesidades, y la respuesta es simple: donde tengan menor precio. Dado que en nuestro pa\u00eds el gobierno insiste en regalar la gasolina, en otorgar subsidios desproporcionados, o en imponer precios que ni siquiera cubren los costos de producci\u00f3n y distribuci\u00f3n de m\u00faltiples productos de consumo masivo, los precios de venta de muchos de esos art\u00edculos son artificialmente bajos y muy inferiores a los existentes al otro lado de la frontera, haciendo que aquel planteamiento de arbitraje sea obvio: comprar los productos en Venezuela para satisfacer las necesidades de los consumidores, o para revenderlos a un precio mucho mayor en el lado colombiano.<\/p>\n<p>Eso no siempre fue as\u00ed. Hace ya varios a\u00f1os, cuando el bol\u00edvar era una moneda fuerte y sobrevaluada, hab\u00eda libertad cambiaria y se mantuvo un tipo de cambio fijo por varias d\u00e9cadas, \u00a0resultaba muy atractivo pasar a C\u00facuta para comprar alimentos, ropa, calzado y otros productos, pues all\u00ed eran m\u00e1s baratos que en Venezuela. Recuerdo v\u00edvidamente que cuando uno viajaba desde la ciudad fronteriza de San Antonio a San Crist\u00f3bal, eran m\u00faltiples las alcabalas de la Guardia Nacional que revisaban exhaustivamente los autom\u00f3viles y transportes de\u00a0 carga para determinar si llevaban mercanc\u00eda colombiana oculta, que se pretend\u00eda introducir a Venezuela sin cumplir los debidos tr\u00e1mites aduanales ni pagar los aranceles respectivos. Ahora la situaci\u00f3n es opuesta, y c\u00f3mo no lo va a ser si muchos productos de consumo masivo tienen en Colombia precios tres y m\u00e1s veces mayores que en Venezuela, para no hablar de la gasolina que aqu\u00ed se regala, pero que en el otro lado de la frontera se vende a m\u00e1s de un d\u00f3lar el gal\u00f3n. Con raz\u00f3n no son solo los llamados \u201cpimpineros\u201d los que se llevan el combustible, sino que el mismo se env\u00eda en gandolas debidamente custodiadas para cuidar su valioso cargamento.<\/p>\n<p>Tambi\u00e9n es conocido el lucrativo negocio de extracci\u00f3n y ulterior importaci\u00f3n de productos, el cual consiste en enviar bienes y semovientes a Colombia que luego se reenv\u00edan a Venezuela en forma de exportaci\u00f3n, siendo \u00e9stos pagados con d\u00f3lares preferenciales artificialmente baratos, divisas cuyo precio en el mercado paralelo de frontera puede llegar a ser hasta cien veces mayor \u00a0al tipo de cambio oficial al que se adquirieron para realizar la operaci\u00f3n.<\/p>\n<p>Recientemente, un alto vocero gubernamental dijo que al cerrarse la frontera se hab\u00eda puesto un torniquete que hab\u00eda parado la hemorragia de productos que se escapaban a Colombia, dando a entender que esa era la gran soluci\u00f3n al problema del contrabando de extracci\u00f3n. Nada m\u00e1s alejado de la verdad. Si bien esa absurda acci\u00f3n oficial pudo limitar temporalmente el env\u00edo de productos al vecino pa\u00eds, no lo elimin\u00f3. Por el contrario, el negocio ha continuado, ahora con extraordinarios sobrecargos de precios, y volver\u00e1 a florecer con toda fuerza en un futuro inmediato, ya que mientras este siga siendo tan lucrativo, los contrabandistas de siempre, de aqu\u00ed y de all\u00e1, seguir\u00e1n actuando impunemente. Solo cuando se eliminen las absurdas distorsiones cambiarias y de precios que hoy existen, y que se siguen ensanchando, es que se podr\u00e1 producir una normalizaci\u00f3n en las actividades comerciales fronterizas.<\/p>\n<p>Nota: Fotograf\u00eda tomada del blog PRODAVINCI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las razones que ha aducido el gobierno venezolano para justificar el cierre de la frontera con Colombia es eliminar la desviaci\u00f3n masiva de productos venezolanos hacia el vecino pa\u00eds. \u00bfPor qu\u00e9 se produce ese contrabando de extracci\u00f3n? \u00bfPuede esa acci\u00f3n de cierre eliminarlo o controlarlo?<\/p>\n","protected":false},"author":2,"featured_media":203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,20,17,21,23,22,26],"tags":[],"class_list":["post-176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-opinion","category-aspectos-cambiarios","category-economia-venezolana","category-inflacion","category-petroleo","category-politica-economica","category-sector-externo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El contrabando fronterizo - Pedro A. Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El contrabando fronterizo - Pedro A. Palma\" \/>\n<meta property=\"og:description\" content=\"Una de las razones que ha aducido el gobierno venezolano para justificar el cierre de la frontera con Colombia es eliminar la desviaci\u00f3n masiva de productos venezolanos hacia el vecino pa\u00eds. \u00bfPor qu\u00e9 se produce ese contrabando de extracci\u00f3n? \u00bfPuede esa acci\u00f3n de cierre eliminarlo o controlarlo?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro A. Palma\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-24T18:51:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-30T18:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/\"},\"author\":{\"name\":\"Pedro Palma\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\"},\"headline\":\"El contrabando fronterizo\",\"datePublished\":\"2015-09-24T18:51:59+00:00\",\"dateModified\":\"2015-09-30T18:30:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/\"},\"wordCount\":699,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Contrabando-fronterizo.-Sep.-20152.jpg\",\"articleSection\":[\"Art\u00edculos de opini\u00f3n\",\"Aspectos cambiarios\",\"Econom\u00eda venezolana\",\"Inflaci\u00f3n\",\"Petr\u00f3leo\",\"Pol\u00edtica econ\u00f3mica\",\"Sector externo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/\",\"name\":\"El contrabando fronterizo - Pedro A. Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Contrabando-fronterizo.-Sep.-20152.jpg\",\"datePublished\":\"2015-09-24T18:51:59+00:00\",\"dateModified\":\"2015-09-30T18:30:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Contrabando-fronterizo.-Sep.-20152.jpg\",\"contentUrl\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Contrabando-fronterizo.-Sep.-20152.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/el-contrabando-fronterizo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El contrabando fronterizo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/\",\"name\":\"Pedro A. Palma\",\"description\":\"Economista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pedroapalma.com\\\/site\\\/#\\\/schema\\\/person\\\/427852d245d06b78d8491abf8b114228\",\"name\":\"Pedro Palma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g\",\"caption\":\"Pedro Palma\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El contrabando fronterizo - Pedro A. Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/","og_locale":"es_ES","og_type":"article","og_title":"El contrabando fronterizo - Pedro A. Palma","og_description":"Una de las razones que ha aducido el gobierno venezolano para justificar el cierre de la frontera con Colombia es eliminar la desviaci\u00f3n masiva de productos venezolanos hacia el vecino pa\u00eds. \u00bfPor qu\u00e9 se produce ese contrabando de extracci\u00f3n? \u00bfPuede esa acci\u00f3n de cierre eliminarlo o controlarlo?","og_url":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/","og_site_name":"Pedro A. Palma","article_published_time":"2015-09-24T18:51:59+00:00","article_modified_time":"2015-09-30T18:30:46+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg","type":"image\/jpeg"}],"author":"Pedro Palma","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pedro Palma","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#article","isPartOf":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/"},"author":{"name":"Pedro Palma","@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228"},"headline":"El contrabando fronterizo","datePublished":"2015-09-24T18:51:59+00:00","dateModified":"2015-09-30T18:30:46+00:00","mainEntityOfPage":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/"},"wordCount":699,"commentCount":0,"image":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#primaryimage"},"thumbnailUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg","articleSection":["Art\u00edculos de opini\u00f3n","Aspectos cambiarios","Econom\u00eda venezolana","Inflaci\u00f3n","Petr\u00f3leo","Pol\u00edtica econ\u00f3mica","Sector externo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/","url":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/","name":"El contrabando fronterizo - Pedro A. Palma","isPartOf":{"@id":"https:\/\/pedroapalma.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#primaryimage"},"image":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#primaryimage"},"thumbnailUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg","datePublished":"2015-09-24T18:51:59+00:00","dateModified":"2015-09-30T18:30:46+00:00","author":{"@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228"},"breadcrumb":{"@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#primaryimage","url":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg","contentUrl":"https:\/\/pedroapalma.com\/site\/wp-content\/uploads\/2015\/09\/Contrabando-fronterizo.-Sep.-20152.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/pedroapalma.com\/site\/el-contrabando-fronterizo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pedroapalma.com\/site\/"},{"@type":"ListItem","position":2,"name":"El contrabando fronterizo"}]},{"@type":"WebSite","@id":"https:\/\/pedroapalma.com\/site\/#website","url":"https:\/\/pedroapalma.com\/site\/","name":"Pedro A. Palma","description":"Economista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedroapalma.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/pedroapalma.com\/site\/#\/schema\/person\/427852d245d06b78d8491abf8b114228","name":"Pedro Palma","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3e6fe7f370f6e5b5d306bf869e784b2a608a86ea1106a224f9e2d9db2e43968?s=96&d=mm&r=g","caption":"Pedro Palma"}}]}},"_links":{"self":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":5,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/176\/revisions"}],"predecessor-version":[{"id":218,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/posts\/176\/revisions\/218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/media\/203"}],"wp:attachment":[{"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/media?parent=176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/categories?post=176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedroapalma.com\/site\/wp-json\/wp\/v2\/tags?post=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}